{"id":12,"date":"2026-07-04T19:03:39","date_gmt":"2026-07-04T17:03:39","guid":{"rendered":"https:\/\/mogz.ovh\/GENET\/?page_id=12"},"modified":"2026-07-08T16:35:19","modified_gmt":"2026-07-08T14:35:19","slug":"nos-partenaires-des-acteurs-essentiels-de-notre-projet-club","status":"publish","type":"page","link":"https:\/\/mogz.ovh\/GENET\/nos-partenaires-des-acteurs-essentiels-de-notre-projet-club\/","title":{"rendered":"Partenaires"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aux Gen\u00eats d\u2019Anglet, la formation des jeunes constitue la priorit\u00e9 de notre projet sportif. Pour offrir \u00e0 nos licenci\u00e9s les meilleures conditions de pratique, nous pouvons compter sur le soutien pr\u00e9cieux de nos partenaires entreprises. Gr\u00e2ce \u00e0 leur engagement, le club est en mesure d&rsquo;investir dans l&rsquo;encadrement sportif, le mat\u00e9riel, les infrastructures et l&rsquo;organisation d&rsquo;\u00e9v\u00e9nements qui participent \u00e0 la progression de nos jeunes joueuses et joueurs.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Un partenariat au service du territoire<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Soutenir les Gen\u00eats d\u2019Anglet, c\u2019est bien plus qu\u2019accompagner un club de football. C\u2019est contribuer au d\u00e9veloppement d&rsquo;une association qui rassemble pr\u00e8s de 700 licenci\u00e9s, favorise l&rsquo;inclusion, transmet des valeurs \u00e9ducatives fortes et participe activement \u00e0 la vie locale. Les entreprises partenaires deviennent ainsi des acteurs engag\u00e9s du territoire, en soutenant un projet qui place la jeunesse, l&rsquo;\u00e9ducation et le vivre-ensemble au c\u0153ur de ses actions.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Merci \u00e0 nos partenaires<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Les Gen\u00eats d\u2019Anglet remercient chaleureusement l&rsquo;ensemble des entreprises qui nous font confiance. Leur soutien est indispensable \u00e0 la r\u00e9ussite de notre projet sportif et \u00e9ducatif. Aujourd&rsquo;hui comme demain, nous continuerons \u00e0 construire avec eux un club ambitieux, formateur et profond\u00e9ment ancr\u00e9 dans les valeurs du Pays Basque.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Devenez partenaire des Gen\u00eats d\u2019Anglet et participez \u00e0 la r\u00e9ussite de plus de 700 passionn\u00e9s de football.<\/strong><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">La Real Sociedad<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Le partenariat entre la Real Sociedad et les Gen\u00eats d\u2019Anglet Football repr\u00e9sente une opportunit\u00e9 exceptionnelle d\u2019\u00e9change de comp\u00e9tences et de savoir-faire, au b\u00e9n\u00e9fice des \u00e9ducateurs, dirigeants et joueurs du club angloy. Gr\u00e2ce \u00e0 cette collaboration, les jeunes talents des Gen\u00eats peuvent \u00e9galement participer \u00e0 des matchs et tournois sous les couleurs de la Real Sociedad, vivant ainsi une exp\u00e9rience sportive et humaine unique au plus haut niveau. Ce lien privil\u00e9gi\u00e9 contribue au d\u00e9veloppement des joueurs et joueuses du club tout en renfor\u00e7ant l\u2019attractivit\u00e9 et l\u2019ambition du projet sportif des Gen\u00eats d\u2019Anglet.<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-7387b849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:18.82%\">\n<figure class=\"wp-block-image aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"148\" height=\"148\" src=\"https:\/\/mogz.ovh\/GENET\/wp-content\/uploads\/2026\/07\/telechargement.png\" alt=\"\" class=\"wp-image-476\"\/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:27.95%\">\n<figure class=\"wp-block-image aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/mogz.ovh\/GENET\/wp-content\/uploads\/2026\/07\/724848901_871967858705273_8278900732134067794_n-768x1024.jpg\" alt=\"\" class=\"wp-image-479\" style=\"aspect-ratio:0.7499911130070029;width:167px;height:auto\" srcset=\"https:\/\/mogz.ovh\/GENET\/wp-content\/uploads\/2026\/07\/724848901_871967858705273_8278900732134067794_n-768x1024.jpg 768w, https:\/\/mogz.ovh\/GENET\/wp-content\/uploads\/2026\/07\/724848901_871967858705273_8278900732134067794_n-225x300.jpg 225w, https:\/\/mogz.ovh\/GENET\/wp-content\/uploads\/2026\/07\/724848901_871967858705273_8278900732134067794_n-1152x1536.jpg 1152w, https:\/\/mogz.ovh\/GENET\/wp-content\/uploads\/2026\/07\/724848901_871967858705273_8278900732134067794_n.jpg 1440w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:28.23%\">\n<figure class=\"wp-block-image aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"418\" height=\"478\" src=\"https:\/\/mogz.ovh\/GENET\/wp-content\/uploads\/2026\/07\/images-4.jpg\" alt=\"\" class=\"wp-image-477\" style=\"aspect-ratio:0.8744665134602758;width:196px;height:auto\" srcset=\"https:\/\/mogz.ovh\/GENET\/wp-content\/uploads\/2026\/07\/images-4.jpg 418w, https:\/\/mogz.ovh\/GENET\/wp-content\/uploads\/2026\/07\/images-4-262x300.jpg 262w\" sizes=\"auto, (max-width: 418px) 100vw, 418px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:25%\">\n<figure class=\"wp-block-image aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/mogz.ovh\/GENET\/wp-content\/uploads\/2026\/07\/649275918_1530922689040906_23752534620536413_n-768x1024.jpg\" alt=\"\" class=\"wp-image-488\" style=\"width:170px;height:auto\" srcset=\"https:\/\/mogz.ovh\/GENET\/wp-content\/uploads\/2026\/07\/649275918_1530922689040906_23752534620536413_n-768x1024.jpg 768w, https:\/\/mogz.ovh\/GENET\/wp-content\/uploads\/2026\/07\/649275918_1530922689040906_23752534620536413_n-225x300.jpg 225w, https:\/\/mogz.ovh\/GENET\/wp-content\/uploads\/2026\/07\/649275918_1530922689040906_23752534620536413_n-1152x1536.jpg 1152w, https:\/\/mogz.ovh\/GENET\/wp-content\/uploads\/2026\/07\/649275918_1530922689040906_23752534620536413_n.jpg 1500w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure>\n<\/div>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aux Gen\u00eats d\u2019Anglet, la formation des jeunes constitue la priorit\u00e9 de notre projet sportif. Pour offrir \u00e0 nos licenci\u00e9s les meilleures conditions de pratique, nous pouvons compter sur le soutien pr\u00e9cieux de nos partenaires entreprises. Gr\u00e2ce \u00e0 leur engagement, le club est en mesure d&rsquo;investir dans l&rsquo;encadrement sportif, le mat\u00e9riel, les infrastructures et l&rsquo;organisation d&rsquo;\u00e9v\u00e9nements [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-12","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/mogz.ovh\/GENET\/wp-json\/wp\/v2\/pages\/12","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mogz.ovh\/GENET\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/mogz.ovh\/GENET\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/mogz.ovh\/GENET\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mogz.ovh\/GENET\/wp-json\/wp\/v2\/comments?post=12"}],"version-history":[{"count":10,"href":"https:\/\/mogz.ovh\/GENET\/wp-json\/wp\/v2\/pages\/12\/revisions"}],"predecessor-version":[{"id":660,"href":"https:\/\/mogz.ovh\/GENET\/wp-json\/wp\/v2\/pages\/12\/revisions\/660"}],"wp:attachment":[{"href":"https:\/\/mogz.ovh\/GENET\/wp-json\/wp\/v2\/media?parent=12"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}